{"id":53642,"date":"2022-01-10T13:35:26","date_gmt":"2022-01-10T18:35:26","guid":{"rendered":"https:\/\/www.psi.org\/?post_type=star_publication&#038;p=53642"},"modified":"2023-10-09T14:44:00","modified_gmt":"2023-10-09T18:44:00","slug":"sop-for-hiv-self-screening-distribution-model-community-based-distribution","status":"publish","type":"star_publication","link":"https:\/\/www.psi.org\/fr\/star_publication\/sop-for-hiv-self-screening-distribution-model-community-based-distribution\/","title":{"rendered":"SOP pour le mod\u00e8le de distribution de l'autod\u00e9pistage du VIH - Distribution communautaire"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"53642\" class=\"elementor elementor-53642\" data-elementor-post-type=\"star_publication\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4327f3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4327f3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d520c1\" data-id=\"0d520c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfa6d52 elementor-widget elementor-widget-text-editor\" data-id=\"dfa6d52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L'objectif principal de ces SOP est de fournir une approche standardis\u00e9e de la distribution des kits d'autod\u00e9pistage du VIH (HIVSS) dans les sites de distribution de SFH. Cette SOP doit \u00eatre utilis\u00e9e par les distributeurs de kits d'autod\u00e9pistage du VIH, les conseillers en d\u00e9pistage du VIH, les prestataires de soins de sant\u00e9, les formateurs et les responsables sur la mani\u00e8re de mettre en \u0153uvre les canaux et modalit\u00e9s de distribution des kits d'autod\u00e9pistage du VIH dans le cadre du programme d'autod\u00e9pistage du VIH. Il doit \u00eatre utilis\u00e9 comme un guide dans les districts de mise en \u0153uvre et doit permettre de cibler les personnes difficiles \u00e0 atteindre ou non diagnostiqu\u00e9es. Les modalit\u00e9s de distribution, mises en \u0153uvre par le biais de l'autod\u00e9pistage, ne sont pas destin\u00e9es \u00e0 remplacer mais plut\u00f4t \u00e0 compl\u00e9ter les services traditionnels de d\u00e9pistage sanguin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"template":"","star_resource_type":[2273,2270],"star_language":[2177],"star_country":[2210],"star_population_served":[2219],"star_health_area":[2235,2234],"class_list":["post-53642","star_publication","type-star_publication","status-publish","has-post-thumbnail","hentry","star_resource_type-standard-operating-procedure-sop","star_resource_type-toolkit","star_language-english","star_country-south-africa","star_population_served-general-population","star_health_area-hiv","star_health_area-hivst"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/star_publication\/53642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/star_publication"}],"about":[{"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/types\/star_publication"}],"version-history":[{"count":0,"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/star_publication\/53642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/media\/53608"}],"wp:attachment":[{"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/media?parent=53642"}],"wp:term":[{"taxonomy":"star_resource_type","embeddable":true,"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/star_resource_type?post=53642"},{"taxonomy":"star_language","embeddable":true,"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/star_language?post=53642"},{"taxonomy":"star_country","embeddable":true,"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/star_country?post=53642"},{"taxonomy":"star_population_served","embeddable":true,"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/star_population_served?post=53642"},{"taxonomy":"star_health_area","embeddable":true,"href":"https:\/\/www.psi.org\/fr\/wp-json\/wp\/v2\/star_health_area?post=53642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}